{"id":7296,"date":"2020-01-24T18:23:25","date_gmt":"2020-01-24T23:23:25","guid":{"rendered":"https:\/\/www.tuxtla.tecnm.mx\/?p=7296"},"modified":"2020-01-24T18:24:14","modified_gmt":"2020-01-24T23:24:14","slug":"concluye-capacitacion-en-planes-de-negocios","status":"publish","type":"post","link":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/concluye-capacitacion-en-planes-de-negocios\/","title":{"rendered":"Concluye capacitaci\u00f3n en Planes de Negocios"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tuxtla.tecnm.mx\/wp-content\/uploads\/2020\/01\/portada_FND.png\" alt=\"\" class=\"wp-image-7295\" width=\"291\" height=\"180\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de curso-taller de tres d\u00edas denominado \u201cPlaneaci\u00f3n Estrat\u00e9gica en los Negocios\u201d acad\u00e9micos de diversas carreras del Tecnol\u00f3gico concluyeron el m\u00f3dulo <strong>\u201cEntidad Financiera y Otorgamiento de Apoyos\u201d<\/strong> impartido por el <strong>Ing. Juan Moreno de la Higuera<\/strong>, del \u00e1rea de Promoci\u00f3n Empresarial de la <strong>Financiera Nacional de Desarrollo Agropecuario, Rural, Forestal y Pesquero (FND).<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>FND<\/strong> es\nuna instituci\u00f3n descentralizada del gobierno federal coordinada con la Secretar\u00eda\nde Hacienda y Cr\u00e9dito Publico y la Comisi\u00f3n Nacional Bancaria de Valores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta instituci\u00f3n\ntiene como funci\u00f3n principal dar financiamiento al sector agropecuario, rural, forestal\ny pesquero desde el 2002. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La FND vino a sustituir a BanRural y se encuentra en transici\u00f3n para convertirse en <strong>FINAGRO<\/strong>, que ser\u00e1 el nuevo rostro de la instituci\u00f3n como parte de la nueva pol\u00edtica p\u00fablica implementada por el presidente de la rep\u00fablica.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tuxtla.tecnm.mx\/wp-content\/uploads\/2020\/01\/82896089_3709742569050840_5181064245105655808_o.jpg\" alt=\"\" class=\"wp-image-7292\" width=\"580\" height=\"394\"\/><figcaption>Participantes del curso<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEste curso va\ndirigido a catedr\u00e1ticos de diversas carreras con la intenci\u00f3n de darles a\nconocer los programas y productos de cr\u00e9dito que maneja la instituci\u00f3n y que tiene\npara estos sectores; en este tenor se dieron a conocer los productos de cr\u00e9dito,\nlas tazas de inter\u00e9s, los programas de financiamiento, a que sectores se\natienden, siendo el mercado objetivo poblaciones rurales no mayores a 50 mil habitantes\u201d<\/em> comparti\u00f3 <strong>Juan Moreno de la Higuera <\/strong>sobre\nlos alcances del curso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este tercer m\u00f3dulo conforma el cierre de una serie de m\u00f3dulos de formaci\u00f3n como parte del curso-taller <strong>\u201cPlaneaci\u00f3n Estrat\u00e9gica en los Negocios\u201d<\/strong> que se llev\u00f3 a cabo del 20 al 24 de enero y que se logr\u00f3 concretar gracias al acuerdo de colaboraci\u00f3n entre el <strong>TecNM campus Tuxtla Guti\u00e9rrez <\/strong>y la <strong>Secretar\u00eda de Econom\u00eda Municipal<\/strong> representada por <strong>David Zamora Rinc\u00f3n<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"553\" src=\"https:\/\/www.tuxtla.tecnm.mx\/wp-content\/uploads\/2020\/01\/83513330_3709742832384147_31609026563276800_o.jpg\" alt=\"\" class=\"wp-image-7294\"\/><figcaption>Participante del curso<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el curso,\nlos acad\u00e9micos del Tec recibieron capacitaci\u00f3n en temas como:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Importancia\nde la formulaci\u00f3n de planes de negocios.<\/li><li>Metodolog\u00eda\npara la formulaci\u00f3n de planes de negocios.<\/li><li>Planes\nde negocios.<\/li><li>Modelo\ntalento emprendedor.<\/li><li>Estudio\nde mercado.<\/li><li>An\u00e1lisis\nde costos.<\/li><li>Estudio\nt\u00e9cnico. Distribuci\u00f3n de planta con software.<\/li><li>Entidad\nfinanciera y otorgamientos de apoyo.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"> Al finalizar los m\u00f3dulos, todos los participantes del curso trabajaron por equipos en la formulaci\u00f3n de un plan de negocios y presentaron las propuestas generadas. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"622\" height=\"470\" src=\"https:\/\/www.tuxtla.tecnm.mx\/wp-content\/uploads\/2020\/01\/82961887_3709742125717551_4681052845519142912_o.jpg\" alt=\"\" class=\"wp-image-7293\"\/><figcaption>El instructor <strong>Juan Moreno de la Higuera<\/strong>, de <strong>Financiera Nacional de Desarrollo Agropecuario, Rural, Forestal y Pesquero (FND).<\/strong> <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ciencia y Tecnolog\u00eda con Sentido Humano<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Instituto\nTecnol\u00f3gico de Tuxtla Guti\u00e9rrez<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Departamento\nde Comunicaci\u00f3n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de curso-taller de tres d\u00edas denominado \u201cPlaneaci\u00f3n Estrat\u00e9gica en los Negocios\u201d acad\u00e9micos de diversas carreras del Tecnol\u00f3gico concluyeron el m\u00f3dulo \u201cEntidad Financiera y Otorgamiento de Apoyos\u201d impartido por el Ing. Juan Moreno de la Higuera, del \u00e1rea de Promoci\u00f3n Empresarial de la Financiera Nacional de Desarrollo Agropecuario, Rural, Forestal y Pesquero (FND).<\/p>\n<p><a href=\"https:\/\/www.tuxtla.tecnm.mx\/dcab\/concluye-capacitacion-en-planes-de-negocios\/\"><span class=\"glyphicon glyphicon-arrow-right\"><\/span>&nbsp;Seguir leyendo<\/a><\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7296","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/posts\/7296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/comments?post=7296"}],"version-history":[{"count":2,"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/posts\/7296\/revisions"}],"predecessor-version":[{"id":7298,"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/posts\/7296\/revisions\/7298"}],"wp:attachment":[{"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/media?parent=7296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/categories?post=7296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tuxtla.tecnm.mx\/dcab\/wp-json\/wp\/v2\/tags?post=7296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}